{"id":189,"count":2,"description":"","link":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/","name":"Christmas","slug":"christmas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Christmas - Antonio Sotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/antoniosotos.com\/en\/tag\/christmas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christmas - Antonio Sotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/antoniosotos.com\/en\/tag\/christmas\/\" \/>\n<meta property=\"og:site_name\" content=\"Antonio Sotos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/antoniosotos.com\\\/en\\\/tag\\\/christmas\\\/\",\"url\":\"https:\\\/\\\/antoniosotos.com\\\/en\\\/tag\\\/christmas\\\/\",\"name\":\"Christmas - Antonio Sotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antoniosotos.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/antoniosotos.com\\\/en\\\/tag\\\/christmas\\\/#breadcrumb\"},\"inLanguage\":\"ENH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/antoniosotos.com\\\/en\\\/tag\\\/christmas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/antoniosotos.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christmas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/antoniosotos.com\\\/#website\",\"url\":\"https:\\\/\\\/antoniosotos.com\\\/\",\"name\":\"Antonio Sotos\",\"description\":\"Fabricante de Azafr\u00e1n, Piment\u00f3n y Especias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/antoniosotos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ENH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christmas - Antonio Sotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/","og_locale":"en_US","og_type":"article","og_title":"Christmas - Antonio Sotos","og_url":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/","og_site_name":"Antonio Sotos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/","url":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/","name":"Christmas - Antonio Sotos","isPartOf":{"@id":"https:\/\/antoniosotos.com\/#website"},"breadcrumb":{"@id":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/#breadcrumb"},"inLanguage":"ENH"},{"@type":"BreadcrumbList","@id":"https:\/\/antoniosotos.com\/en\/tag\/christmas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/antoniosotos.com\/en\/"},{"@type":"ListItem","position":2,"name":"Christmas"}]},{"@type":"WebSite","@id":"https:\/\/antoniosotos.com\/#website","url":"https:\/\/antoniosotos.com\/","name":"Antonio Sotos","description":"Fabricante de Azafr\u00e1n, Piment\u00f3n y Especias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/antoniosotos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ENH"}]}},"_links":{"self":[{"href":"https:\/\/antoniosotos.com\/en\/wp-json\/wp\/v2\/tags\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antoniosotos.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/antoniosotos.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/antoniosotos.com\/en\/wp-json\/wp\/v2\/posts?tags=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}